{"id":4964,"date":"2022-03-15T14:31:11","date_gmt":"2022-03-15T13:31:11","guid":{"rendered":"https:\/\/www.myes.school\/?page_id=4964"},"modified":"2025-12-09T12:49:07","modified_gmt":"2025-12-09T11:49:07","slug":"corsi-di-inglese-catania","status":"publish","type":"page","link":"https:\/\/www.myes.school\/it\/corsi-di-inglese-catania\/","title":{"rendered":"Corsi di inglese a Catania"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4964\" class=\"elementor elementor-4964\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d72607a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d72607a\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-82e6a28\" data-id=\"82e6a28\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-00b5f0a acenter elementor-widget elementor-widget-wgl-double-headings\" data-id=\"00b5f0a\" data-element_type=\"widget\" data-widget_type=\"wgl-double-headings.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wgl-double_heading\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-91cd7e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"91cd7e1\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e46ba5b\" data-id=\"e46ba5b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-301731af acenter elementor-widget elementor-widget-wgl-double-headings\" data-id=\"301731af\" data-element_type=\"widget\" data-widget_type=\"wgl-double-headings.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wgl-double_heading\"><div class=\"dbl__subtitle\"><span>PERCH\u00c9 SCEGLIERLO<\/span><\/div><div class=\"dbl__title-wrapper\"><span class=\"dbl__title dbl-title_1\">Perch\u00e8 siamo diversi<\/span><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbc6650 elementor-widget elementor-widget-text-editor\" data-id=\"dbc6650\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Se cerchi una scuola di inglese a Catania smart e innovativa che si adatti alle tue necessit\u00e0<br \/>My English School \u00e8 quella che fa per te.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40092ae4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"40092ae4\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1d8a9fac\" data-id=\"1d8a9fac\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63db30bd acenter elementor-widget elementor-widget-wgl-double-headings\" data-id=\"63db30bd\" data-element_type=\"widget\" data-widget_type=\"wgl-double-headings.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wgl-double_heading\"><div class=\"dbl__title-wrapper\"><span class=\"dbl__title dbl-title_1\">Welcome Pack MyES<\/span><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a7a0e47 elementor-widget elementor-widget-text-editor\" data-id=\"1a7a0e47\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Grandi offerte per grandi obiettivi<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b135c76 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b135c76\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7b58c59e\" data-id=\"7b58c59e\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e7fe2db elementor-widget elementor-widget-global elementor-global-6535 elementor-widget-image\" data-id=\"4e7fe2db\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"370\" height=\"330\" src=\"https:\/\/www.myes.school\/wp-content\/uploads\/2022\/10\/corsi-di-inglese-per-adulti.png\" class=\"attachment-full size-full wp-image-140965\" alt=\"studenti dei corsi di inglese per adulti myES\" srcset=\"https:\/\/www.myes.school\/wp-content\/uploads\/2022\/10\/corsi-di-inglese-per-adulti.png 370w, https:\/\/www.myes.school\/wp-content\/uploads\/2022\/10\/corsi-di-inglese-per-adulti-300x268.png 300w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e338b51 acenter elementor-widget elementor-widget-wgl-info-box\" data-id=\"2e338b51\" data-element_type=\"widget\" data-widget_type=\"wgl-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a class=\"wgl-infobox__link\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6NjcyNywidG9nZ2xlIjpmYWxzZX0%3D\" id=\"offerType1Btn\"><\/a><div class=\"wgl-infobox\"><div class=\"wgl-infobox_wrapper\"><div class=\"content_wrapper\"><div class=\"wgl-infobox-title_wrapper\"><h3 class=\"wgl-infobox_title\"><span class=\"wgl-infobox_title-idle\">Inglese per adulti<\/span><\/h3><\/div><div class=\"wgl-infobox_content\"><p class=\"list-welcome\">6 livelli MySmart<\/p><p class=\"list-welcome\">Insegnanti madrelingua<\/p><p class=\"list-welcome\">2 ore settimanali<\/p><p class=\"list-welcome\">Lezioni in piccoli gruppi<\/p><\/div><div class=\"wgl-infobox-button_wrapper\"><div  class=\"wgl-infobox_button button-read-more\"><span>SCARICA IL LISTINO PREZZI<\/span><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-42edf2bc\" data-id=\"42edf2bc\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;,&quot;animation_delay&quot;:500}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71a3c901 elementor-widget elementor-widget-global elementor-global-6538 elementor-widget-image\" data-id=\"71a3c901\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"370\" height=\"330\" src=\"https:\/\/www.myes.school\/wp-content\/uploads\/2022\/10\/lezione-di-inglese-online.png\" class=\"attachment-full size-full wp-image-140919\" alt=\"studentessa durante una lezione di inglese online\" srcset=\"https:\/\/www.myes.school\/wp-content\/uploads\/2022\/10\/lezione-di-inglese-online.png 370w, https:\/\/www.myes.school\/wp-content\/uploads\/2022\/10\/lezione-di-inglese-online-300x268.png 300w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44a8f11e acenter elementor-widget elementor-widget-wgl-info-box\" data-id=\"44a8f11e\" data-element_type=\"widget\" data-widget_type=\"wgl-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a class=\"wgl-infobox__link\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6NjcyNywidG9nZ2xlIjpmYWxzZX0%3D\" id=\"offerType2Btn\"><\/a><div class=\"wgl-infobox\"><div class=\"wgl-infobox_wrapper\"><div class=\"content_wrapper\"><div class=\"wgl-infobox-title_wrapper\"><h3 class=\"wgl-infobox_title\"><span class=\"wgl-infobox_title-idle\">Inglese online<\/span><\/h3><\/div><div class=\"wgl-infobox_content\"><p class=\"list-welcome\">6 livelli MySmart<\/p><p class=\"list-welcome\">Insegnanti madrelingua<\/p><p class=\"list-welcome\">2 ore settimanali<\/p><p class=\"list-welcome\">Attivit\u00e0 online<\/p><\/div><div class=\"wgl-infobox-button_wrapper\"><div  class=\"wgl-infobox_button button-read-more\"><span>SCARICA IL LISTINO PREZZI<\/span><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-680a693c\" data-id=\"680a693c\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;,&quot;animation_delay&quot;:1000}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2cc50326 elementor-widget elementor-widget-global elementor-global-6541 elementor-widget-image\" data-id=\"2cc50326\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"370\" height=\"330\" src=\"https:\/\/www.myes.school\/wp-content\/uploads\/2022\/10\/studentessa-certificazione-myes.png\" class=\"attachment-full size-full wp-image-140961\" alt=\"studentessa per la certificazione di inglese B2\" srcset=\"https:\/\/www.myes.school\/wp-content\/uploads\/2022\/10\/studentessa-certificazione-myes.png 370w, https:\/\/www.myes.school\/wp-content\/uploads\/2022\/10\/studentessa-certificazione-myes-300x268.png 300w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67cadac4 acenter elementor-widget elementor-widget-wgl-info-box\" data-id=\"67cadac4\" data-element_type=\"widget\" data-widget_type=\"wgl-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a class=\"wgl-infobox__link\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6NjcyNywidG9nZ2xlIjpmYWxzZX0%3D\" id=\"offerType3Btn\"><\/a><div class=\"wgl-infobox\"><div class=\"wgl-infobox_wrapper\"><div class=\"content_wrapper\"><div class=\"wgl-infobox-title_wrapper\"><h3 class=\"wgl-infobox_title\"><span class=\"wgl-infobox_title-idle\">Certificazioni B2<\/span><\/h3><\/div><div class=\"wgl-infobox_content\"><p class=\"list-welcome\">Insegnanti madrelingua<\/p>\n<p class=\"list-welcome\">Lezioni in piccoli gruppi<\/p>\n<p class=\"list-welcome\">Preparazione in 4 settimane<\/p>\n<p class=\"list-welcome\">Simulazione d'esame compresa<\/p><\/div><div class=\"wgl-infobox-button_wrapper\"><div  class=\"wgl-infobox_button button-read-more\"><span>SCARICA IL LISTINO PREZZI<\/span><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e848dec elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e848dec\" data-element_type=\"section\" id=\"form\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2851a358\" data-id=\"2851a358\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ba43000 aleft elementor-widget-icon-box wgl-icon-box elementor-view-default elementor-widget elementor-widget-global elementor-global-6415 elementor-widget-wgl-info-box\" data-id=\"5ba43000\" data-element_type=\"widget\" data-widget_type=\"wgl-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wgl-infobox\"><div class=\"wgl-infobox_wrapper wgl-layout-left\"><div class=\"media-wrapper icon-wrapper\"><span class=\"wgl-icon\" ><span class=\"icon elementor-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"a\" width=\"20mm\" height=\"20mm\" viewBox=\"0 0 56.69 56.69\"><circle cx=\"28.35\" cy=\"28.35\" r=\"28.35\" style=\"fill:#0f1f3d;\"><\/circle><g><path d=\"M33.02,10.03v13.9h23.33c-.12-.75-.27-1.48-.44-2.21h-8.93l7.21-5.01c-.56-1.23-1.19-2.41-1.91-3.54l-12.31,8.55h-2.58l14.07-9.78c-.47-.66-.97-1.3-1.49-1.92h-16.95Zm2.21,10.51V12.23h11.95l-11.95,8.31Z\" style=\"fill:#fff;\"><\/path><path d=\"M23.69,10.03H6.72c-1,1.18-1.91,2.44-2.71,3.78l11.39,7.91h-2.66L3.27,15.13c-.35,.66-.67,1.33-.97,2.01l6.58,4.57H.79c-.17,.73-.32,1.46-.44,2.21H23.69V10.03Zm-2.21,11.05L8.76,12.23h12.73v8.84Z\" style=\"fill:#fff;\"><\/path><path d=\"M21.49,46.69h2.21v-13.92H.35c.12,.75,.27,1.48,.44,2.21H9.41l-6.98,4.85c.55,1.23,1.18,2.42,1.89,3.56l12.1-8.41h2.63l-13.68,9.51h-.33c.47,.68,.98,1.35,1.51,1.99l.9,.22h14.04Zm0-10.72v8.51H9.24l12.25-8.51Z\" style=\"fill:#fff;\"><\/path><path d=\"M40.98,34.98h2.9l9.53,6.62c.35-.66,.67-1.33,.97-2.01l-6.63-4.61h8.16c.17-.73,.32-1.46,.44-2.21h-23.33v13.92h16.22l.9-.22c.9-1.08,1.72-2.22,2.45-3.42l-11.61-8.07Zm-5.75,9.51v-8.63l12.42,8.63h-12.42Z\" style=\"fill:#fff;\"><\/path><\/g><\/svg><\/span><\/span><\/div><div class=\"content_wrapper\"><div class=\"wgl-infobox-title_wrapper\"><span class=\"wgl-infobox_title\"><span class=\"wgl-infobox_title-idle\">INSEGNANTI MADRELINGUA<\/span><\/span><\/div><div class=\"wgl-infobox_content\"><div class=\"elementor-element elementor-element-4b6c2ea elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit aleft elementor-widget-icon-box wgl-icon-box elementor-view-default elementor-widget elementor-widget-wgl-info-box\" data-id=\"4b6c2ea\" data-element_type=\"widget\" data-widget_type=\"wgl-info-box.default\"><div class=\"elementor-widget-container\"><div class=\"wgl-infobox\"><div class=\"wgl-infobox_wrapper wgl-layout-left\"><div class=\"content_wrapper\"><div class=\"wgl-infobox_content\"><div class=\"elementor-element elementor-element-4b6c2ea elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit aleft elementor-widget-icon-box wgl-icon-box elementor-view-default elementor-widget elementor-widget-wgl-info-box\" data-id=\"4b6c2ea\" data-element_type=\"widget\" data-widget_type=\"wgl-info-box.default\"><div class=\"elementor-widget-container\"><div class=\"wgl-infobox\"><div class=\"wgl-infobox_wrapper wgl-layout-left\"><div class=\"content_wrapper\"><div class=\"wgl-infobox_content\"><p><span>I nostri insegnanti sono madrelingua\u00a0<\/span><br \/><span>e native level certificati con esperienza<\/span><\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-192f48b5 aleft elementor-widget-icon-box wgl-icon-box elementor-view-default elementor-widget elementor-widget-global elementor-global-6418 elementor-widget-wgl-info-box\" data-id=\"192f48b5\" data-element_type=\"widget\" data-widget_type=\"wgl-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wgl-infobox\"><div class=\"wgl-infobox_wrapper wgl-layout-left\"><div class=\"media-wrapper icon-wrapper\"><span class=\"wgl-icon\" ><span class=\"icon elementor-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"a\" width=\"20mm\" height=\"20mm\" viewBox=\"0 0 56.69 56.69\"><path d=\"M28.35,0h0C44,0,56.69,12.69,56.69,28.35s-12.69,28.35-28.35,28.35S0,44,0,28.35,12.69,0,28.35,0\" style=\"fill:#0f1f3d;\"><\/path><path d=\"M46.55,20.48c-1.09-.67-2.39-.95-3.69-.81l-.39-.34c-3.31-2.96-8.62-4.61-14.59-4.53-5.77,.07-10.93,1.78-13.81,4.57l-.29,.29c-1.28-.11-2.57,.17-3.63,.82-1.13,.7-1.68,1.81-1.53,3.14,.16,1.45,.99,2.45,2.32,2.8,.18,.05,.36,.08,.55,.11,0,.3,0,.6,.03,.91l.12,1.27c.27,2.84,.55,5.77,.9,8.66,.09,.72,.43,2.21,1.77,2.66l.11,1.87h5.02v-1.71h17.75l.12,1.73h4.84l.13-1.93c1.04-.37,1.55-.88,1.84-2.43,.37-2,.66-4.13,.88-6.34,.13-1.3,.17-2.62,.21-3.89,0-.26,.02-.51,.03-.77,.1-.01,.19-.03,.29-.06,1.43-.33,2.33-1.3,2.53-2.73,.2-1.41-.32-2.54-1.5-3.27Zm-20.22-3.44c.25-.02,.5-.03,.75-.05,.26,0,.53-.02,.8-.02,.66-.01,1.31,.01,1.95,.05,4.28,.22,8.11,1.35,10.98,3.23-1.12,.54-2.02,1.41-2.55,2.49-.49,.99-.87,2.18-1.16,3.63-.17,.82-.24,1.65-.3,2.46-2.13-.49-4.24-.4-6.29-.32-.72,.03-1.47,.06-2.19,.06-.72,0-1.43-.03-2.19-.06-2.03-.09-4.11-.18-6.21,.39-.02-.35-.06-.7-.13-1.06-.07-.33-.14-.66-.21-.99-.27-1.35-.56-2.74-1.14-4.05-.5-1.13-1.44-2.04-2.62-2.59,2.49-1.65,5.92-2.75,9.75-3.09,.25-.03,.51-.05,.77-.06Zm19.55,6.4c-.07,.53-.31,.77-.86,.9-.16,.04-.35,.05-.57,.07-.13,.01-.26,.02-.4,.04l-.93,.1-.04,.93c-.03,.58-.05,1.16-.06,1.74-.04,1.3-.08,2.52-.2,3.75-.21,2.15-.49,4.22-.85,6.16-.1,.53-.17,.66-.17,.67-.1,.08-.59,.21-.83,.27l-.76,.2-.1,1.43h-.76l-.12-1.73H17.25v1.71h-.77l-.11-1.81-1.1,.08c-.27,.02-.45,.03-.56-.86-.34-2.86-.62-5.78-.89-8.61l-.12-1.27c-.03-.33-.02-.69-.01-1.06,0-.19,0-.39,0-.58v-.93l-.92-.15c-.19-.03-.36-.05-.53-.08-.3-.04-.54-.07-.74-.13-.38-.1-.63-.29-.7-.92-.06-.5,.08-.78,.5-1.03,.89-.55,2.06-.67,3.12-.34,.95,.29,1.67,.89,2.02,1.69,.48,1.08,.73,2.3,.99,3.59,.07,.34,.14,.68,.21,1.02,.09,.39,.09,.83,.11,1.34,0,.26,.01,.54,.03,.82l.09,1.55,1.43-.6c2.16-.91,4.38-.82,6.74-.72,.75,.03,1.52,.07,2.28,.06,.76,0,1.53-.03,2.27-.06,2.38-.1,4.62-.19,6.82,.59l1.31,.46,.14-1.39c.04-.4,.07-.79,.1-1.17,.06-.84,.12-1.62,.27-2.37,.26-1.26,.58-2.28,.98-3.1,.4-.82,1.19-1.45,2.16-1.73,1.05-.3,2.15-.17,3.02,.37,.37,.23,.57,.48,.48,1.11Z\" style=\"fill:#fff;\"><\/path><\/svg><\/span><\/span><\/div><div class=\"content_wrapper\"><div class=\"wgl-infobox-title_wrapper\"><span class=\"wgl-infobox_title\"><span class=\"wgl-infobox_title-idle\">AMBIENTE CONFORTEVOLE<\/span><\/span><\/div><div class=\"wgl-infobox_content\"><p><span>Le nostre aule sono moderni open<\/span><br \/><span>space con comodi divani e poltroncine<\/span><\/p><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62de9e9c aleft elementor-widget-icon-box wgl-icon-box elementor-view-default elementor-widget elementor-widget-global elementor-global-6421 elementor-widget-wgl-info-box\" data-id=\"62de9e9c\" data-element_type=\"widget\" data-widget_type=\"wgl-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wgl-infobox\"><div class=\"wgl-infobox_wrapper wgl-layout-left\"><div class=\"media-wrapper icon-wrapper\"><span class=\"wgl-icon\" ><span class=\"icon elementor-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"a\" width=\"20mm\" height=\"20mm\" viewBox=\"0 0 56.69 56.69\"><path d=\"M28.35,0h0C44,0,56.69,12.69,56.69,28.35s-12.69,28.35-28.35,28.35S0,44,0,28.35,12.69,0,28.35,0\" style=\"fill:#0f1f3d;\"><\/path><g><path d=\"M28.29,9.61c-10.22,0-18.54,8.31-18.54,18.54s8.31,18.53,18.54,18.53,18.54-8.31,18.54-18.53S38.51,9.61,28.29,9.61Zm1.11,34.81v-3.68c0-.61-.49-1.1-1.1-1.1s-1.1,.49-1.1,1.1v3.68c-8.13-.54-14.63-7.05-15.18-15.17h3.59c.61,0,1.1-.49,1.1-1.1s-.49-1.1-1.1-1.1h-3.59c.55-8.12,7.05-14.63,15.17-15.17v3.68c0,.61,.49,1.1,1.1,1.1s1.1-.49,1.1-1.1v-3.68c8.13,.55,14.63,7.05,15.18,15.17h-3.78c-.61,0-1.1,.49-1.1,1.1s.49,1.1,1.1,1.1h3.78c-.55,8.12-7.05,14.62-15.17,15.17Z\" style=\"fill:#fff;\"><\/path><polygon points=\"28.31 28.28 23.23 23.47 21.71 25.07 28.36 31.35 38.11 21.6 36.55 20.04 28.31 28.28\" style=\"fill:#fff;\"><\/polygon><\/g><\/svg><\/span><\/span><\/div><div class=\"content_wrapper\"><div class=\"wgl-infobox-title_wrapper\"><span class=\"wgl-infobox_title\"><span class=\"wgl-infobox_title-idle\">CORSI FLESSIBILI<\/span><\/span><\/div><div class=\"wgl-infobox_content\"><p><span>I corsi MyES sono personalizzati e\u00a0<\/span><br \/><span>ti permettono di imparare l'inglese con grande flessibilit\u00e0!<\/span><\/p><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-21c599cd\" data-id=\"21c599cd\" data-element_type=\"column\" id=\"contatti\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25bcfb91 acenter elementor-widget elementor-widget-wgl-double-headings\" data-id=\"25bcfb91\" data-element_type=\"widget\" data-widget_type=\"wgl-double-headings.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wgl-double_heading\"><div class=\"dbl__title-wrapper\"><span class=\"dbl__title dbl-title_1\">Contattaci<\/span><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70d85c3e elementor-widget elementor-widget-global elementor-global-6565 elementor-widget-text-editor\" data-id=\"70d85c3e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span>Se vuoi maggiori informazioni, consigli o per saperne di pi\u00f9, compila questo modulo. Ti ricontatteremo il prima possibile.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-151fe1ba elementor-widget elementor-widget-spacer\" data-id=\"151fe1ba\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49db97fd elementor-widget elementor-widget-shortcode\" data-id=\"49db97fd\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><form class=\"new-website-custom-form\" action=\"\/wp-content\/themes\/unicoach-child\/submits\/generic_form_submit.php\" method=\"post\" id=\"contactForm_inpage\"><div class=\"row \"><input type=\"hidden\" name=\"testtest\" value=\"f795be39b4\" required><input type=\"hidden\" name=\"form_page\" value=\"4964\" required><input type=\"hidden\" name=\"form_page_title\" value=\"Corsi di inglese a Catania\" required><input type=\"hidden\" name=\"page_uq\" value=\"873cfbb2-bb14-45d3-ac72-4ca09b370e94\" required><input type=\"hidden\" id=\"referral\" name=\"referral\" value=\"\"><input type=\"hidden\" name=\"lang\" value=\"it\"><input type=\"hidden\" name=\"thx_page\" value=\"\"><div class=\"wgl_col-12\"><input class=\"w-100\" type=\"text\" name=\"name\" placeholder=\"Nome\" required maxlength=\"50\"><\/div><div class=\"wgl_col-12\"><input class=\"w-100\" type=\"text\" name=\"surname\" placeholder=\"Cognome\" required maxlength=\"50\"><\/div><div class=\"wgl_col-12\"><input class=\"w-100\" type=\"email\" name=\"email\" placeholder=\"Email\" required><\/div><div class=\"wgl_col-12\"><input class=\"w-100\" type=\"tel\" pattern=\"^[0-9 +()-]{6,15}$\" name=\"phone\" placeholder=\"Telefono\" required><\/div><div class=\"wgl_col-12 qui-confirm\"><select name=\"school\" required><option value=\"75\">Catania Tribunale<\/option><\/select><\/div><div class=\"wgl_col-12 new-form-control-bar-it d-none\"><input class=\"w-100\" type=\"text\" pattern=\"[0-9]{5,10}\" name=\"zipcode\" placeholder=\"CAP\" value><\/div><input type=\"hidden\" id=\"gclid_field\" name=\"gclid_field\" value=\"\"><div class=\"wgl_col-12 privacy-form\"><label><input class=\"general-form-privacy\" type=\"checkbox\" name=\"privacy\" required>In quanto di et\u00e0 superiore ai 16 anni, dichiaro di acconsentire al trattamento dei miei dati personali in conformit\u00e0 all\u2019<a target=\"_blank\" href=\"https:\/\/www.myes.school\/wp-content\/uploads\/2024\/03\/Privacy-MyES-03.24.pdf\" target=\"_blank\">informativa privacy<\/a>.<\/label><\/div><div class=\"wgl_col-12 privacy-form privacy_optional\"><label><input class=\"general-form-privacy-optional\" type=\"checkbox\" name=\"privacy_optional\">Desidero ricevere comunicazioni commerciali e promozionali relative ai prodotti e servizi a marchio MyES\u00a0<\/label><\/div><div class=\"wgl_col-12 privacy-form\"><span style=\"font-size:10px;\"> ** le sedi contrassegnate con * offrono sempre solo corsi online<\/span><\/div><div class=\"wgl_col-12\"><button class=\"general-form-cta g-recaptcha\" data-sitekey=\"6LfzUQohAAAAAHsCskqqOk4lXySy5vePxpFbgi6q\" data-callback=\"onSubmit\" data-action=\"submit\" type=\"submit\">Richiedi informazioni<\/button><\/div><\/div><script type=\"text\/javascript\">var __ss_noform = __ss_noform || [];__ss_noform.push(['baseURI', 'https:\/\/app-3QNDKEDZ0Y.marketingautomation.services\/webforms\/receivePostback\/MzawMDEzMzS2BAA\/']);__ss_noform.push(['endpoint', '873cfbb2-bb14-45d3-ac72-4ca09b370e94']);<\/script><script type=\"text\/javascript\" src=\"https:\/\/koi-3QNDKEDZ0Y.marketingautomation.services\/client\/noform.js?ver=1.24\" ><\/script><\/form><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-63ef7b36 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"63ef7b36\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ed6a64c\" data-id=\"1ed6a64c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-400b7c73 acenter elementor-widget elementor-widget-wgl-double-headings\" data-id=\"400b7c73\" data-element_type=\"widget\" data-widget_type=\"wgl-double-headings.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wgl-double_heading\"><h3 class=\"dbl__title-wrapper\"><span class=\"dbl__title dbl-title_1\">Studiare inglese a Catania<\/span><\/h3><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44e98f8a elementor-widget elementor-widget-global elementor-global-6531 elementor-widget-video\" data-id=\"44e98f8a\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=-XKVOJzXznU&quot;,&quot;lazy_load&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f30ba83 bg-video elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f30ba83\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-45020eb5\" data-id=\"45020eb5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f34b122 elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"6f34b122\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-323b9ff9 elementor-widget elementor-widget-text-editor\" data-id=\"323b9ff9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span>Se vuoi imparare l\u2019inglese in un\u00a0<\/span><strong>ambiente confortevole<\/strong><span>\u00a0e simulando\u00a0<\/span><strong>contesti di<span>\u00a0<\/span><em>real-life<\/em><\/strong><span>, My English School \u00e8 la scuola di inglese a Catania che fa per te! Da noi, raggiungi i tuoi obiettivi linguistici, non solo grazie a lezioni di grammatica e conversazione ma anche attraverso la costante socializzazione con gli altri studenti e gli insegnanti.\u00a0<\/span><strong>Attivit\u00e0 extra-didattiche,<\/strong><span>\u00a0una\u00a0<\/span><strong>piattaforma digitale<\/strong><span>\u00a0per esercitarti ovunque ti trovi e\u00a0<\/span><strong>teachers madrelingua e native level<\/strong><span>\u00a0sempre pronti a sostenerti: tutto ci\u00f2 \u00e8 My English School!<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4db53b70 acenter elementor-widget elementor-widget-wgl-button\" data-id=\"4db53b70\" data-element_type=\"widget\" data-widget_type=\"wgl-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"button-wrapper\"><a  class=\"wgl-button btn-size-lg \" role=\"button\" href=\"#contatti\"><div class=\"button-content-wrapper \"><span class=\"wgl-button-text\">CONTATTACI<\/span><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7a0471ed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7a0471ed\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a1d8885\" data-id=\"a1d8885\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1bd38ada elementor-widget elementor-widget-spacer\" data-id=\"1bd38ada\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21cab553 elementor-widget elementor-widget-heading\" data-id=\"21cab553\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">LA NOSTRA SEDE A CATANIA<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fe37864 elementor-widget elementor-widget-text-editor\" data-id=\"7fe37864\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span>Scegli la scuola My English School pi\u00f9 vicina per contattarla: insieme sceglieremo il percorso pi\u00f9 adatto a te!<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-573339d7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"573339d7\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e435384\" data-id=\"1e435384\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c035f76 elementor-widget elementor-widget-heading\" data-id=\"6c035f76\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">My English School Catania<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47516cc3 elementor-widget elementor-widget-text-editor\" data-id=\"47516cc3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span>viale XX Settembre 45\/E,\u00a0<\/span><br \/><a href=\"tel:095 8743343\">095 8743343<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42a16411 elementor-widget elementor-widget-global elementor-global-6590 elementor-widget-image\" data-id=\"42a16411\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"72\" height=\"18\" src=\"https:\/\/www.myes.school\/wp-content\/uploads\/2022\/03\/Trustpilot_brandmark_gr-blk_RGB-72x18-S.png\" class=\"attachment-large size-large wp-image-5296\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-374a686 elementor-widget elementor-widget-text-editor\" data-id=\"374a686\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p><div class=\"trustpilot-widget\" data-locale=\"it-IT\" data-template-id=\"5418015fb0d04a0c9cf721f2\" data-businessunit-id=\"5f88122760a97a000131e0b0\" data-style-height=\"30px\" data-style-width=\"100%\" data-theme=\"light\" data-location=\"CT\" data-stars=\"4,5\" data-review-languages=\"it\" data-font-family=\"Montserrat\"><a href=\"https:\/\/it.trustpilot.com\/review\/myes.school\" target=\"_blank\" rel=\"noopener\">Trustpilot<\/a><\/div><p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4af256d acenter elementor-widget elementor-widget-wgl-button\" data-id=\"4af256d\" data-element_type=\"widget\" data-widget_type=\"wgl-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"button-wrapper\"><a  class=\"wgl-button btn-size-md \" role=\"button\" href=\"#contatti\"><div class=\"button-content-wrapper \"><span class=\"wgl-button-text\">Contatta la sede<\/span><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-32780f23 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"32780f23\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4350eef1\" data-id=\"4350eef1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a63bfc1 elementor-widget elementor-widget-jet-map\" data-id=\"2a63bfc1\" data-element_type=\"widget\" data-widget_type=\"jet-map.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-map\" data-init=\"{&quot;center&quot;:{&quot;lat&quot;:37.51488993348267,&quot;lng&quot;:15.09079540737451},&quot;zoom&quot;:15,&quot;scrollwheel&quot;:true,&quot;zoomControl&quot;:true,&quot;fullscreenControl&quot;:true,&quot;streetViewControl&quot;:true,&quot;mapTypeControl&quot;:true,&quot;pinsAutoClose&quot;:false}\" data-pins=\"[{&quot;address&quot;:&quot;London Eye, London, United Kingdom&quot;,&quot;position&quot;:{&quot;lat&quot;:37.51488993348267,&quot;lng&quot;:15.09079540737451},&quot;desc&quot;:&quot;&lt;p&gt;Viale XX Settembre, 45\\\\E, 95128 Catania CT&lt;\\\/p&gt;&quot;,&quot;state&quot;:&quot;hidden&quot;,&quot;image&quot;:&quot;https:\\\/\\\/www.myes.school\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/info-s.png&quot;,&quot;link_title&quot;:&quot;Direzione&quot;,&quot;link&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/g.page\\\/myenglishschoolmilanomeravigli?share&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;}}]\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b116f8b elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"5b116f8b\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3411f970\" data-id=\"3411f970\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74e14762 elementor-arrows-position-inside elementor-widget elementor-widget-global elementor-global-6544 elementor-widget-image-carousel\" data-id=\"74e14762\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carosello d&#039;immagini\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.myes.school\/wp-content\/uploads\/2022\/10\/aula-scuola-di-inglese-myes.webp\" alt=\"aula della scuola di inglese myes\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.myes.school\/wp-content\/uploads\/2022\/10\/corsi-di-inglese.webp\" alt=\"studenti durante un corso di inglese myes\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.myes.school\/wp-content\/uploads\/2022\/10\/scuola-di-inglese-myes.webp\" alt=\"sede della scuola di inglese myes\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.myes.school\/wp-content\/uploads\/2022\/10\/lezioni-di-inglese.webp\" alt=\"lezione di inglese myes\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3cc7793c\" data-id=\"3cc7793c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6bc1a5e elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6bc1a5e\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f84a5d8\" data-id=\"f84a5d8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-094af93 col-mobile-3 elementor-widget__width-initial elementor-widget-mobile__width-initial col-3 col-tablet-2 elementor-widget elementor-widget-global elementor-global-168043 elementor-widget-wgl-gallery\" data-id=\"094af93\" data-element_type=\"widget\" data-widget_type=\"wgl-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wgl-gallery\"><div class=\"wgl-gallery_items \"><div class=\"wgl-gallery_item-wrapper\"><div class=\"wgl-gallery_item\"><img decoding=\"async\" class=\"wgl-gallery_image\" src=\"https:\/\/www.myes.school\/wp-content\/uploads\/2024\/03\/logo-widget-ielts-1468x940.png\" alt=\"\" \/><\/div><\/div><div class=\"wgl-gallery_item-wrapper\"><div class=\"wgl-gallery_item\"><img decoding=\"async\" class=\"wgl-gallery_image\" src=\"https:\/\/www.myes.school\/wp-content\/uploads\/2022\/10\/certificato-language-cert-e1705504918763-143x98.webp\" alt=\"language cert\" \/><\/div><\/div><div class=\"wgl-gallery_item-wrapper\"><a class=\"wgl-gallery_item\" href=\"https:\/\/certificazioni.tuttoeuropa.it\/\" target=\"_blank\"><img decoding=\"async\" class=\"wgl-gallery_image\" src=\"https:\/\/www.myes.school\/wp-content\/uploads\/2024\/10\/WePrepare_2024-2025_RGB-560x324.png\" alt=\"\" \/><\/a><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-41e7b13d elementor-widget elementor-widget-heading\" data-id=\"41e7b13d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">La tua scuola di inglese a Catania<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40bd2a5a elementor-widget elementor-widget-text-editor\" data-id=\"40bd2a5a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span>Se stai cercando un corso di inglese su misura per te<strong>&nbsp;a Catania, la soluzione migliore \u00e8 senza dubbio My English School!<\/strong><\/span><\/p>\n<p>MyES garantisce <strong>corsi di inglese personalizzati<\/strong>, uno staff che ti seguir\u00e0 passo dopo passo e moltissimi&nbsp;<strong>eventi extra-didattici&nbsp;<\/strong>per imparare l\u2019inglese in maniera dinamica e stimolante!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b2349f4 aleft a-mobilecenter elementor-widget-icon-box wgl-icon-box elementor-widget elementor-widget-wgl-button\" data-id=\"4b2349f4\" data-element_type=\"widget\" data-widget_type=\"wgl-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"button-wrapper\"><a  class=\"wgl-button btn-size-md \" role=\"button\" href=\"#contatti\"><div class=\"button-content-wrapper align-icon-right\"><div class=\"media-wrapper icon-wrapper\"><span class=\"wgl-icon\" ><i class=\"icon elementor-icon flaticon flaticon-arrowsoutline\" aria-hidden=\"true\"><\/i><\/span><\/div><span class=\"wgl-button-text\">Richiedi informazioni<\/span><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-81c2e0b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"81c2e0b\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e0fb6f1\" data-id=\"e0fb6f1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78c8f2f elementor-widget elementor-widget-heading\" data-id=\"78c8f2f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQ<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-84375a3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"84375a3\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-76fd611\" data-id=\"76fd611\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69d17a7 elementor-widget elementor-widget-spacer\" data-id=\"69d17a7\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8a7fa37 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8a7fa37\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1db5cec\" data-id=\"1db5cec\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b38dea elementor-view-default elementor-widget elementor-widget-wgl-toggle-accordion\" data-id=\"3b38dea\" data-element_type=\"widget\" data-widget_type=\"wgl-toggle-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wgl-accordion icon-plus\" id=\"wgl-accordion-3b38dea\" data-type=\"accordion\"><div class=\"wgl-accordion_panel\"><h4 id=\"wgl-accordion_header-6201\" class=\"wgl-accordion_header\" data-default=\"\"><span class=\"wgl-accordion_title\">Quali sono i prezzi dei corsi di inglese a Catania di MyES?<\/span><i class=\"wgl-accordion_icon elementor-icon \"><\/i><\/h4><div class=\"wgl-accordion_content\"><p><span style=\"font-weight: 400;\">Il <\/span><b>corso di inglese a Catania <\/b><span style=\"font-weight: 400;\">di MyES, ha costi variabili. Sono disponibili pi\u00f9 opzioni, tra cui lezioni con costi orari, mensili o basati sul livello. Di seguito sono riportati i dettagli specifici dei costi:<\/span><\/p><p><span style=\"font-weight: 400;\">Costo orario a partire da: 17\u20ac<\/span><\/p><p><span style=\"font-weight: 400;\">Costo mensile a partire da: 139\u20ac<\/span><\/p><p><span style=\"font-weight: 400;\">Costo per livello a partire da: 556\u20ac<\/span><\/p><\/div><\/div><div class=\"wgl-accordion_panel\"><h4 id=\"wgl-accordion_header-6202\" class=\"wgl-accordion_header\" data-default=\"\"><span class=\"wgl-accordion_title\">MyES offre corsi di inglese gratis a Catania?<\/span><i class=\"wgl-accordion_icon elementor-icon \"><\/i><\/h4><div class=\"wgl-accordion_content\"><p><span style=\"font-weight: 400;\">Certamente! MyES ti offre la possibilit\u00e0 di partecipare a tre <\/span><b>lezioni gratis di inglese a Catania<\/b><span style=\"font-weight: 400;\">, in modo da vivere direttamente un'anteprima dei servizi offerti dalla nostra scuola. Questa opportunit\u00e0 ti permetter\u00e0 di valutare se le nostre lezioni del corso sono adatte alle tue esigenze e di prendere una decisione informata. Inoltre, avrai l'opportunit\u00e0 di iniziare a conoscere i futuri compagni di corso.<\/span><\/p><\/div><\/div><div class=\"wgl-accordion_panel\"><h4 id=\"wgl-accordion_header-6203\" class=\"wgl-accordion_header\" data-default=\"\"><span class=\"wgl-accordion_title\">Si pu\u00f2 ottenere la certificazione B2 con la scuola di inglese di Catania di MyES?<\/span><i class=\"wgl-accordion_icon elementor-icon \"><\/i><\/h4><div class=\"wgl-accordion_content\"><p><span style=\"font-weight: 400;\">S\u00ec, MyES offre <\/span><b>corsi di inglese a Catania con certificazioni <\/b><span style=\"font-weight: 400;\">riconosciute dal Ministero dell'Istruzione e del Merito, come ad esempio <\/span><b>LanguageCert <\/b><span style=\"font-weight: 400;\">e le certificazioni di livello <\/span><b>livello B1 <\/b><span style=\"font-weight: 400;\">e <\/span><b>B2<\/b><span style=\"font-weight: 400;\">. Attraverso i nostri corsi dedicati, ti accompagneremo in un percorso di apprendimento e preparazione specifico per l'esame di inglese prescelto. Durante questo periodo, ti verr\u00e0 insegnato un metodo molto pratico, che ti aiuter\u00e0 ad affrontare l'esame con sicurezza.<\/span><\/p><\/div><\/div><div class=\"wgl-accordion_panel\"><h4 id=\"wgl-accordion_header-6204\" class=\"wgl-accordion_header\" data-default=\"\"><span class=\"wgl-accordion_title\">MyES prevede anche corsi di inglese per ragazzi a Catania?<\/span><i class=\"wgl-accordion_icon elementor-icon \"><\/i><\/h4><div class=\"wgl-accordion_content\"><p><span style=\"font-weight: 400;\">La <\/span><b>scuola per imparare l\u2019inglese a Catania <\/b><span style=\"font-weight: 400;\">di MyES, offre corsi sia per ragazzi, che per adulti e studenti, in base alle tue esigenze formative. Se hai l'intenzione di apprendere o <\/span><b>migliorare l'inglese<\/b><span style=\"font-weight: 400;\"> e stai cercando un aiuto nella scelta del percorso, indipendentemente dall'et\u00e0 o dal tuo livello attuale, MyES ha sicuramente il corso che stai cercando!<\/span><\/p><\/div><\/div><div class=\"wgl-accordion_panel\"><h4 id=\"wgl-accordion_header-6205\" class=\"wgl-accordion_header\" data-default=\"\"><span class=\"wgl-accordion_title\">Gli insegnanti dei corsi di inglese a Catania di MyES sono tutti madrelingua?<\/span><i class=\"wgl-accordion_icon elementor-icon \"><\/i><\/h4><div class=\"wgl-accordion_content\"><p><span style=\"font-weight: 400;\">La <\/span><b>scuola di inglese a Catania<\/b><span style=\"font-weight: 400;\"> di MyES offre lezioni tenute esclusivamente da docenti madrelingua e native level altamente qualificati nell'insegnamento dell'inglese. Il loro principale obiettivo \u00e8 accompagnarti nel processo di apprendimento della lingua e farti immergere completamente nella cultura inglese. Durante le lezioni, viene data grande importanza alla pratica della comunicazione in inglese, utilizzando approcci basati su situazioni reali della vita quotidiana. I nostri <\/span><b>corsi di conversazione in inglese a Catania <\/b><span style=\"font-weight: 400;\">sono appositamente pensati per offrirti un'esperienza pratica e aiutarti a raggiungere una padronanza completa della lingua.<\/span><\/p><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a8734b1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a8734b1\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-362f436\" data-id=\"362f436\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63447eb elementor-widget elementor-widget-html\" data-id=\"63447eb\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p><script type=\"application\/ld+json\">{\r\n    \"@context\": \"http:\/\/schema.org\",\r\n    \"@type\": \"Product\",\r\n    \"name\": \"Corso di inglese Catania\",\r\n    \"image\": \"\",\r\n    \"sku\": \"undefined\",\r\n    \"aggregateRating\": {\r\n        \"@type\": \"AggregateRating\",\r\n        \"bestRating\": \"5\",\r\n        \"ratingValue\": \"5\",\r\n        \"reviewCount\": \"89\",\r\n        \"worstRating\": 1\r\n    },\r\n    \"review\": [\r\n        {\r\n            \"@type\": \"Review\",\r\n            \"author\": \"cliente\",\r\n            \"datePublished\": \"2023-07-31T09:17:28\",\r\n            \"description\": \"Ottima scuola di inglese che punta molto sulla conversazione e sulla pratica facendo in modo che a poco a poco si perda quell\u2019imbarazzo nel parlare una lingua diversa dalla propria. Ottima organizzazione anche delle lezioni online, classi piccole e ottimi docenti.\",\r\n            \"reviewRating\": {\r\n                \"@type\": \"Rating\",\r\n                \"bestRating\": \"5\",\r\n                \"ratingValue\": \"4\",\r\n                \"worstRating\": \"1\"\r\n            },\r\n            \"reviewBody\": \"Ottima scuola di inglese che punta molto sulla conversazione e sulla pratica facendo in modo che a poco a poco si perda quell\u2019imbarazzo nel parlare una lingua diversa dalla propria. Ottima organizzazione anche delle lezioni online, classi piccole e ottimi docenti.\"\r\n        }\r\n    ]\r\n}\r\n<\/script><\/p>\r\n<script type=\"application\/ld+json\">\r\n{\r\n  \"@context\": \"https:\/\/schema.org\",\r\n  \"@type\": [\"EducationalOrganization\", \"LocalBusiness\", \"Organization\"],\r\n  \"name\": \"My English School - Corsi di inglese a Catania\",\r\n  \"url\": \"https:\/\/www.myes.school\/it\/corsi-di-inglese-catania\/\",\r\n  \"logo\": \"https:\/\/www.myes.school\/wp-content\/uploads\/2023\/12\/Logo-MyES-Square.png\",\r\n  \"image\": \"https:\/\/www.myes.school\/wp-content\/uploads\/2022\/10\/scuola-di-inglese-myes.webp\",\r\n  \"sameAs\": [\r\n    \"https:\/\/www.instagram.com\/my_english_school_ita\/\",\r\n    \"https:\/\/www.facebook.com\/MyEnglishSchool\/?locale=it_IT\",\r\n    \"https:\/\/www.linkedin.com\/company\/my-english-school-italia\/\",\r\n    \"https:\/\/it.trustpilot.com\/review\/www.myes.school\/location\/catania\"\r\n  ],\r\n  \"address\": {\r\n    \"@type\": \"PostalAddress\",\r\n    \"streetAddress\": \"Viale XX Settembre\",\r\n    \"addressLocality\": \"Catania\",\r\n    \"postalCode\": \"95129\",\r\n    \"addressCountry\": \"IT\"\r\n  }\r\n}\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>PERCH\u00c9 SCEGLIERLOPerch\u00e8 siamo diversi Se cerchi una scuola di inglese a Catania smart e innovativa che si adatti alle tue necessit\u00e0My English School \u00e8 quella che fa per te. Welcome Pack MyES Grandi offerte per grandi obiettivi Inglese per adulti 6 livelli MySmart Insegnanti madrelingua 2 ore settimanali Lezioni in piccoli gruppi SCARICA IL LISTINO [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4964","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.4 (Yoast SEO v26.4) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La miglior scuola di inglese a Catania: ecco i corsi - My English School\u2122<\/title>\n<meta name=\"description\" content=\"Grazie ai corsi personalizzati di MyES Catania, impari l&#039;inglese sulla base delle tue esigenze e dei tuoi obiettivi. Scopri la scuola su misura per te!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corsi di inglese a Catania\" \/>\n<meta property=\"og:description\" content=\"Grazie ai corsi personalizzati di MyES Catania, impari l&#039;inglese sulla base delle tue esigenze e dei tuoi obiettivi. Scopri la scuola su misura per te!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.myes.school\/it\/corsi-di-inglese-catania\/\" \/>\n<meta property=\"og:site_name\" content=\"My English School\u2122\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MyEnglishSchool\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-09T11:49:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.myes.school\/wp-content\/uploads\/2022\/10\/corsi-di-inglese-per-adulti.png\" \/>\n\t<meta property=\"og:image:width\" content=\"370\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"20 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.myes.school\/it\/corsi-di-inglese-catania\/\",\"url\":\"https:\/\/www.myes.school\/it\/corsi-di-inglese-catania\/\",\"name\":\"La miglior scuola di inglese a Catania: ecco i corsi - My English School\u2122\",\"isPartOf\":{\"@id\":\"https:\/\/www.myes.school\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.myes.school\/it\/corsi-di-inglese-catania\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.myes.school\/it\/corsi-di-inglese-catania\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.myes.school\/wp-content\/uploads\/2022\/10\/corsi-di-inglese-per-adulti.png\",\"datePublished\":\"2022-03-15T13:31:11+00:00\",\"dateModified\":\"2025-12-09T11:49:07+00:00\",\"description\":\"Grazie ai corsi personalizzati di MyES Catania, impari l'inglese sulla base delle tue esigenze e dei tuoi obiettivi. Scopri la scuola su misura per te!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.myes.school\/it\/corsi-di-inglese-catania\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.myes.school\/it\/corsi-di-inglese-catania\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.myes.school\/it\/corsi-di-inglese-catania\/#primaryimage\",\"url\":\"https:\/\/www.myes.school\/wp-content\/uploads\/2022\/10\/corsi-di-inglese-per-adulti.png\",\"contentUrl\":\"https:\/\/www.myes.school\/wp-content\/uploads\/2022\/10\/corsi-di-inglese-per-adulti.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.myes.school\/it\/corsi-di-inglese-catania\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.myes.school\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Corsi di inglese a Catania\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.myes.school\/it\/#website\",\"url\":\"https:\/\/www.myes.school\/it\/\",\"name\":\"My English School\u2122\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.myes.school\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.myes.school\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.myes.school\/it\/#organization\",\"name\":\"My English School\u2122\",\"url\":\"https:\/\/www.myes.school\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.myes.school\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.myes.school\/wp-content\/uploads\/2023\/12\/Logo-MyES-Square.png\",\"contentUrl\":\"https:\/\/www.myes.school\/wp-content\/uploads\/2023\/12\/Logo-MyES-Square.png\",\"width\":1080,\"height\":1080,\"caption\":\"My English School\u2122\"},\"image\":{\"@id\":\"https:\/\/www.myes.school\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/MyEnglishSchool\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La miglior scuola di inglese a Catania: ecco i corsi - My English School\u2122","description":"Grazie ai corsi personalizzati di MyES Catania, impari l'inglese sulla base delle tue esigenze e dei tuoi obiettivi. Scopri la scuola su misura per te!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Corsi di inglese a Catania","og_description":"Grazie ai corsi personalizzati di MyES Catania, impari l'inglese sulla base delle tue esigenze e dei tuoi obiettivi. Scopri la scuola su misura per te!","og_url":"https:\/\/www.myes.school\/it\/corsi-di-inglese-catania\/","og_site_name":"My English School\u2122","article_publisher":"https:\/\/www.facebook.com\/MyEnglishSchool","article_modified_time":"2025-12-09T11:49:07+00:00","og_image":[{"width":370,"height":330,"url":"https:\/\/www.myes.school\/wp-content\/uploads\/2022\/10\/corsi-di-inglese-per-adulti.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"20 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.myes.school\/it\/corsi-di-inglese-catania\/","url":"https:\/\/www.myes.school\/it\/corsi-di-inglese-catania\/","name":"La miglior scuola di inglese a Catania: ecco i corsi - My English School\u2122","isPartOf":{"@id":"https:\/\/www.myes.school\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.myes.school\/it\/corsi-di-inglese-catania\/#primaryimage"},"image":{"@id":"https:\/\/www.myes.school\/it\/corsi-di-inglese-catania\/#primaryimage"},"thumbnailUrl":"https:\/\/www.myes.school\/wp-content\/uploads\/2022\/10\/corsi-di-inglese-per-adulti.png","datePublished":"2022-03-15T13:31:11+00:00","dateModified":"2025-12-09T11:49:07+00:00","description":"Grazie ai corsi personalizzati di MyES Catania, impari l'inglese sulla base delle tue esigenze e dei tuoi obiettivi. Scopri la scuola su misura per te!","breadcrumb":{"@id":"https:\/\/www.myes.school\/it\/corsi-di-inglese-catania\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.myes.school\/it\/corsi-di-inglese-catania\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.myes.school\/it\/corsi-di-inglese-catania\/#primaryimage","url":"https:\/\/www.myes.school\/wp-content\/uploads\/2022\/10\/corsi-di-inglese-per-adulti.png","contentUrl":"https:\/\/www.myes.school\/wp-content\/uploads\/2022\/10\/corsi-di-inglese-per-adulti.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.myes.school\/it\/corsi-di-inglese-catania\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.myes.school\/it\/"},{"@type":"ListItem","position":2,"name":"Corsi di inglese a Catania"}]},{"@type":"WebSite","@id":"https:\/\/www.myes.school\/it\/#website","url":"https:\/\/www.myes.school\/it\/","name":"My English School\u2122","description":"","publisher":{"@id":"https:\/\/www.myes.school\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.myes.school\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.myes.school\/it\/#organization","name":"My English School\u2122","url":"https:\/\/www.myes.school\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.myes.school\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.myes.school\/wp-content\/uploads\/2023\/12\/Logo-MyES-Square.png","contentUrl":"https:\/\/www.myes.school\/wp-content\/uploads\/2023\/12\/Logo-MyES-Square.png","width":1080,"height":1080,"caption":"My English School\u2122"},"image":{"@id":"https:\/\/www.myes.school\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MyEnglishSchool"]}]}},"_links":{"self":[{"href":"https:\/\/www.myes.school\/it\/wp-json\/wp\/v2\/pages\/4964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.myes.school\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.myes.school\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.myes.school\/it\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.myes.school\/it\/wp-json\/wp\/v2\/comments?post=4964"}],"version-history":[{"count":83,"href":"https:\/\/www.myes.school\/it\/wp-json\/wp\/v2\/pages\/4964\/revisions"}],"predecessor-version":[{"id":192724,"href":"https:\/\/www.myes.school\/it\/wp-json\/wp\/v2\/pages\/4964\/revisions\/192724"}],"wp:attachment":[{"href":"https:\/\/www.myes.school\/it\/wp-json\/wp\/v2\/media?parent=4964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}